{"id":28430,"count":1,"description":"https:\/\/umwelt.bremen.de\/","link":"https:\/\/renewable-carbon.eu\/news\/supplier\/die-senatorin-fur-umwelt-klima-und-wissenschaft-bremen\/","name":"Die Senatorin f\u00fcr Umwelt, Klima und Wissenschaft - Bremen","slug":"die-senatorin-fur-umwelt-klima-und-wissenschaft-bremen","taxonomy":"supplier","meta":[],"_links":{"self":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier\/28430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier"}],"about":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/taxonomies\/supplier"}],"wp:post_type":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts?supplier=28430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}