{"id":1353,"count":2,"description":"http:\/\/www.artek.fi","link":"https:\/\/renewable-carbon.eu\/news\/supplier\/artek\/","name":"Artek","slug":"artek","taxonomy":"supplier","meta":[],"_links":{"self":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier\/1353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier"}],"about":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/taxonomies\/supplier"}],"wp:post_type":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts?supplier=1353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}