{"id":18858,"date":"2014-01-20T02:00:39","date_gmt":"2014-01-20T00:00:39","guid":{"rendered":"http:\/\/www.innovations-report.de\/html\/berichte\/studien\/weltmaerkte_nahrungsmittel_klimawandel_groesserer_224851.html"},"modified":"2014-01-17T11:22:13","modified_gmt":"2014-01-17T09:22:13","slug":"weltmarkte-fur-nahrungsmittel-klimawandel-groserer-preistreiber-als-die-bioenergie","status":"publish","type":"post","link":"https:\/\/renewable-carbon.eu\/news\/weltmarkte-fur-nahrungsmittel-klimawandel-groserer-preistreiber-als-die-bioenergie\/","title":{"rendered":"Die Landwirtschaft im Zentrum des Klimawandels &#8211; PIK ver\u00f6ffentlicht Studienergebnisse"},"content":{"rendered":"<p><strong>F\u00fcr eine Minderung des Aussto\u00dfes von Treibhausgasen wird zum Erreichen des 2 Grad-Ziels wahrscheinlich ein erheblicher Anteil Bioenergie im Energiemix der Zukunft ben\u00f6tigt. Trotz mancher Risiken w\u00e4ren die Auswirkungen einer steigenden Nachfrage nach Bioenergie auf die Weltagrarm\u00e4rkte weit geringer als die durch einen ungebremsten Klimawandel. Das zeigt nun eine Studie, die unter der Leitung von Wissenschaftlern des Potsdam-Instituts f\u00fcr Klimafolgenforschung ver\u00f6ffentlicht wurde. W\u00e4hrend die Agrarpreise durch direkte Klimawirkungen auf Ernteertr\u00e4ge bis 2050 um etwa 25 Prozent h\u00f6her w\u00e4ren als in einem Szenario ohne Klimawandel, w\u00fcrde eine hohe Nachfrage nach Bioenergie in einem Szenario mit ambitioniertem Klimaschutz die Preise nur um etwa 5 Prozent steigen lassen.<\/strong><\/p>\n<p>Die Analyse wurde mit zwei weiteren Studien unter Leitung des PIK im Rahmen des Agricultural Model Intercomparison and Improvement Project (AgMIP) in einer Sonderausgabe des Journals Agricultural Economics ver\u00f6ffentlicht. Die Ergebnisse zeigen, wie sehr die Landwirtschaft im Zentrum des Klimawandels steht \u2013 sowohl in Hinsicht auf die n\u00f6tige Anpassung an Klimafolgen als auch hinsichtlich ihres Potentials, die globale Erw\u00e4rmung zu begrenzen. Landwirtschaftliche Produktion und Landnutzungsver\u00e4nderungen tragen etwa ein Drittel zu den globalen Treibhausgasemissionen bei.<\/p>\n<h3>Erste AgMIP-Studie: Einsatz von Bioenergie der zweiten Generation<\/h3>\n<p>\u201eBioenergie der zweiten Generation auf Zellulosebasis k\u00f6nnte vor allem langfristig f\u00fcr die Reduzierung von CO<sub>2<\/sub>-Emissionen wichtig werden \u2013 zum Beispiel in Form von Biokraftstoffen im Transportsektor, weil dort alles andere relativ teuer w\u00e4re, etwa die Elektrifizierung\u201c, sagt Leitautor Hermann Lotze-Campen. Die heutige Bioenergieproduktion von derzeit weltweit 40 ExaJoule wird dominiert von Holz zum Heizen und der ersten Generation der Biokraftstoffe wie Ethanol aus Zuckerrohr oder Biodiesel aus \u00d6lsaaten. Im Gegensatz zur ersten Generation der Biokraftstoffe, die direkt mit der Lebensmittel- und Futterproduktion konkurriert, haben die der zweiten Generation das Potential, den Wettbewerb zwischen Nahrungsmittel-Erzeugung und Energiem\u00e4rkten zu verringern sowie die Produktionskosten zu reduzieren.<\/p>\n<p>Der Anstieg der weltweiten Nachfrage nach Bioenergie der zweiten Generation aus Reststoffen aus Wald und Feld, Abf\u00e4llen oder gezielt angebauten Pflanzen wie Miscanthusgras oder Pappeln wird in der Studie auf zus\u00e4tzliche 100 ExaJoule bis im Jahr 2050 veranschlagt (etwa 15 Prozent des weltweiten Prim\u00e4renergiebedarfs), wenn die globale Erw\u00e4rmung langfristig auf zwei Grad \u00fcber dem vorindustriellen Niveau begrenzt werden soll. Die Studie, ein Vergleich zwischen f\u00fcnf agrar\u00f6konomischen Computermodellen, erlaubt erstmals die vorl\u00e4ufige Schlussfolgerung, dass eine ambitionierte Begrenzung des Klimawandels mit Bioenergie nicht zwingend die weltweiten Nahrungsmittelpreise hochtreibt.<\/p>\n<h3>Zweite AgMIP-Studie: Klimawandel l\u00e4sst Bedarf an Ackerfl\u00e4chen wachsen<\/h3>\n<p>In einem umfassenden Vergleich von zehn globalen agrar\u00f6konomischen Simulationen untersuchte Christoph Schmitz vom PIK, wieviel Agrarfl\u00e4chen unter verschiedenen sozio\u00f6konomischen und Klimawandel-Szenarien genutzt w\u00fcrden. \u201eWir sehen, dass die meisten Modelle f\u00fcr Szenarien mit einem ungebremsten Klimawandel einen Zuwachs von Ackerland bis zum Jahr 2050 anzeigen, der mehr als 50 Prozent h\u00f6her ist als bei stabilem Klima\u201c, sagt Schmitz. Die Zunahme w\u00fcrde 320 statt 200 Millionen Hektar betragen \u2013 das entspricht etwa der dreifachen Fl\u00e4che Deutschlands. In allen Simulationen gab es die gr\u00f6\u00dfte Ausbreitung von Ackerfl\u00e4chen in S\u00fcdamerika und in Afrika s\u00fcdlich der Sahara. \u201eUm in diesen Regionen zus\u00e4tzliche Ackerfl\u00e4chen zu gewinnen, werden aber Jahrhunderte alte Regenw\u00e4lder abgeholzt. Das f\u00fchrt nicht nur zu einem Anstieg der CO<sub>2<\/sub>-Emissionen, sondern schadet auch der Artenvielfalt und bedroht wichtige \u00d6kosystemleistungen\u201c, erkl\u00e4rt Schmitz.<\/p>\n<p>Bisher zeigten Projektionen zur zuk\u00fcnftigen Landnutzung aufgrund gro\u00dfer Unsicherheiten bei den Daten und Methoden sehr unterschiedliche Ergebnisse. Um die Unterschiede besser zu verstehen, haben sich die zehn auf diesem Gebiet f\u00fchrenden internationalen Modelliererteams zwei Jahre zusammengesetzt, um voneinander zu lernen und die wichtigsten Daten und Annahmen zu harmonisieren. Das Ergebnis ist dieser einzigartige Modellvergleich, der robustere Absch\u00e4tzungen sowie ein besseres Verst\u00e4ndnis der Zusammenh\u00e4nge zwischen Klimawandel, Landnutzung und Agrarpreisen erm\u00f6glicht.<\/p>\n<h3>Dritte AgMIP-Studie: Klimawirkungen auf Ernteertr\u00e4ge sind stark, aber weltweit sehr unterschiedlich<\/h3>\n<p>Zuk\u00fcnftige Ernten und die Rolle von Klimafolgen f\u00fcr \u00f6konomische Simulationen von Nahrungsmittelm\u00e4rkten stehen im Mittelpunkt einer dritten Studie. Mit Hilfe eines Vergleichs von Computersimulationen wird in dieser Studie untersucht, in welchen Weltregionen der Klimawandel in welchem Ma\u00df die Produktivit\u00e4t von Agrarland beeinflusst. \u201eDie m\u00f6glichen Folgen des Klimawandels f\u00fcr Ernteertr\u00e4ge sind stark, sie sind aber sehr unterschiedlich je nach Region und Kulturpflanze\u201c, sagt Leitautor Christoph M\u00fcller vom PIK.<\/p>\n<p>F\u00fcr die f\u00fcnf wichtigsten Nutzpflanzen Reis, Weizen, Mais, Sojabohnen und Erdn\u00fcsse zeigt die Studie einen vom Klimawandel verursachten R\u00fcckgang der Ertr\u00e4ge um 10 bis 38 Prozent weltweit bis zum Jahr 2050. Dies gilt in einem Szenario ungebremsten Klimawandels, und verglichen mit den derzeitigen Bedingungen. Zur Anpassung gibt es nicht die eine L\u00f6sung f\u00fcr alle Bedingungen. Ein Teil der Produktion k\u00f6nnte in Regionen mit weniger negativen Klimafolgen verlagert werden; andere Regionen k\u00f6nnten von einer Intensivierung der Landwirtschaft profitieren. \u201eUm mit den gro\u00dfen Unterschieden von einer Region zur anderen und von einer Pflanze zur anderen zurecht zu kommen, w\u00e4re ein flexibleres weltweites Handelssystem f\u00fcr landwirtschaftliche G\u00fcter n\u00f6tig\u201c, so M\u00fcller.<\/p>\n<h3>Wichtiger Schritt hin zu robusteren Absch\u00e4tzungen der Klimafolgen f\u00fcr die Landwirtschaft<\/h3>\n<p>Es gibt noch immer betr\u00e4chtliche Unsicherheiten bei den Projektionen zur zuk\u00fcnftigen Landwirtschaft \u2013 etwa den D\u00fcngeeffekt von CO<sub>2,<\/sub> die Verf\u00fcgbarkeit von zus\u00e4tzlichem Agrarland, das Ma\u00df des Zuwachses an landwirtschaftlicher Produktivit\u00e4t. Dennoch sind die AgMIP Ergebnisse ein wichtiger Schritt in Richtung einer robusteren Absch\u00e4tzung von Klimafolgen auf die Landwirtschaft. \u201eD\u00fcrren wie im Jahr 2012 in den USA k\u00f6nnen immense Auswirkungen auf Ernteertr\u00e4ge und Exporte haben\u201c, so Lotze-Campen. \u201eDas zeigt, dass schlechte Ernten in wichtigen Produktionsregionen, auch wenn sie nur in einem \u00fcberschaubaren Gebiet auftreten, einen erheblichen Einfluss auf die Weltagrarm\u00e4rkte, Preise und Nahrungsmittelsicherheit haben k\u00f6nnen. Dieser Effekt k\u00f6nnte sich bei unbegrenztem Klimawandel noch verst\u00e4rken.\u201c<\/p>\n<p><em>Artikel: Lotze-Campen, H., von Lampe, M., Kyle, P., Fujimori, S., Havl\u00edk, P., van Meijl, H., Hasegawa, T., Popp, A., Schmitz, C., Tabeau, A., Valin, H., Willenbockel, D., Wise, M. (2013): Impacts of increased bioenergy demand on global food markets: an AgMIP economic model intercomparison. Agricultural Economics (early view\/online) [doi:10.1111\/agec12092]<\/em><\/p>\n<p><em>Weblink zum Artikel:<a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/agec.12092\/suppinfo\"> http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/agec.12092\/suppinfo<\/a><\/em><\/p>\n<p><em>Artikel: Schmitz, C., van Meijl, H., Kyle, P., Nelson, G.D., Fujimori, S., Gurgel, A., Havl\u00edk, P., Heyhoe, E., Mason d&#8217;Croz, D., Popp, A., Sands, R., Tabeau, A., van der Mensbrugghe, D., von Lampe, M., Wise, M., Blanc, E., Hasegawa, T., Kavallari, A., Valin, H. (2013): Land-use change trajectories up to 2050: insights from a global agro-economic model comparison. Agricultural Economics (early view\/online) [doi:10.1111\/agec.12090]<\/em><\/p>\n<p><em>Weblink zum Artikel:<a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/agec.12090\/suppinfo\"> http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/agec.12090\/suppinfo<\/a><\/em><\/p>\n<p><em>Artikel: M\u00fcller, C., Robertson, R.D. (2013): Projecting future crop productivity for global economic modeling. Agricultural Economics (early view\/online) [doi:10.1111\/agec.12088]<\/em><\/p>\n<p><em>Weblink zum Artikel: <a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/agec.12088\/suppinfo\">http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/agec.12088\/suppinfo<\/a><\/em><\/p>\n<h3><em>\u00dcber AgMIP:<\/em><\/h3>\n<p><em> Das Agricultural Model Intercomparison and Improvement Project (AgMIP) &#8211; zu deutsch: Projekt zum Vergleich und zur Verbesserung von Landwirtschafts-Modellen &#8211; ist der gro\u00df angelegte internationale Versuch, die Modellierer-Gemeinschaften aus Klimaforschung, Nutzpflanzenforschung und Wirtschaftswissenschaft mittels modernster Informationstechnologie zusammen zu bringen, so dass sie die n\u00e4chste Generation von Projektionen zu den Folgen des Klimawandels f\u00fcr die Landwirtschaft entwickeln. Mit dabei sind unter anderem Wissenschaftler von Instituten wie dem Potsdam-Institut f\u00fcr Klimafolgenforschung, dem International Food Policy Research Institute (IFPRI) und dem International Institute for Applied Systems Analysis (IIASA).<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Studien Analysen] Trotz mancher Risiken w&auml;ren die Auswirkungen einer steigenden Nachfrage nach Bioe&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","nova_meta_subtitle":"","footnotes":""},"categories":[5572],"tags":[],"supplier":[1834],"class_list":["post-18858","post","type-post","status-publish","format-standard","hentry","category-bio-based","supplier-potsdam-institut-fuer-klimafolgenforschung-pik"],"_links":{"self":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/18858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/comments?post=18858"}],"version-history":[{"count":0,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/18858\/revisions"}],"wp:attachment":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/media?parent=18858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/categories?post=18858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/tags?post=18858"},{"taxonomy":"supplier","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier?post=18858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}