{"id":175232,"date":"2026-04-02T07:37:00","date_gmt":"2026-04-02T05:37:00","guid":{"rendered":"https:\/\/renewable-carbon.eu\/news\/?p=175232"},"modified":"2026-04-01T11:36:32","modified_gmt":"2026-04-01T09:36:32","slug":"ineratec-und-tertu-grunden-das-joint-venture-t-h2-zum-bau-einer-anlage-fur-synthetische-kraftstoffe-in-der-normandie","status":"publish","type":"post","link":"https:\/\/renewable-carbon.eu\/news\/ineratec-und-tertu-grunden-das-joint-venture-t-h2-zum-bau-einer-anlage-fur-synthetische-kraftstoffe-in-der-normandie\/","title":{"rendered":"INERATEC und TERTU gr\u00fcnden das Joint Venture T.H2 zum Bau einer Anlage f\u00fcr synthetische Kraftstoffe in der Normandie"},"content":{"rendered":"\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png-1024x683.webp\" alt=\"\" class=\"wp-image-175258\" style=\"width:732px;height:auto\" srcset=\"https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png-1024x683.webp 1024w, https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png-300x200.webp 300w, https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png-150x100.webp 150w, https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png-768x512.webp 768w, https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png-400x267.webp 400w, https:\/\/renewable-carbon.eu\/news\/media\/2026\/03\/TH2-Plant-site.png.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p><strong>Das deutsche Cleantech-Unternehmen INERATEC und der franz\u00f6sische Industriekonzern TERTU haben das Joint Venture T.H2 gegr\u00fcndet und damit einen wichtigen Schritt zur Entwicklung einer gemeinsamen Anlage zur Herstellung synthetischer Kraftstoffe in der N\u00e4he von Caen in der Normandie getan. Die Anlage wird im Rahmen des Projekts \u201eBELair\u201c entwickelt, f\u00fcr das die Partner derzeit einen Antrag beim Europ\u00e4ischen Innovationsfonds vorbereiten. T.H2 strebt den Aufbau der ersten Industrieanlage in Frankreich an, die lokal gewonnene Holzreststoffe mithilfe der Fischer-Tropsch-Technologie in nachhaltige synthetische Kraftstoffe und Wachse umwandelt. Die Anlage folgt auf die Inbetriebnahme von ERA ONE, Europas erster e-Fuel-Anlage im kommerziellen Ma\u00dfstab, die 2025 von INERATEC in Betrieb genommen wurde.<\/strong><\/p>\n\n\n\n<p>Das Joint Venture T.H2 vereint das sich erg\u00e4nzende Fachwissen beider Partner. INERATEC bringt seine modulare Gas-to-Liquids-Technologieplattform sowie seine Erfahrung beim Bau, der Inbetriebnahme und dem Betrieb von Industrieanlagen ein, die&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/synthesegas\" rel=\"noreferrer noopener\">Synthesegas<\/a>&nbsp;mittels des Fischer-Tropsch-Verfahrens in synthetische Kraftstoffe und Chemikalien umwandeln. TERTU steuert sein Fachwissen in der Sammlung, Aufbereitung und Verwertung von Holzresten sowie seine starke industrielle Pr\u00e4senz in Frankreich und seine regionalen Partnerschaften in der Normandie bei.&nbsp;<\/p>\n\n\n\n<p>Die Anlage wird j\u00e4hrlich etwa 60.000 Tonnen Holzreststoffe verarbeiten, die aus den regionalen W\u00e4ldern und der Industrie stammen. Die Holzreststoffe werden mittels Vergasung in&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/synthesegas\" rel=\"noreferrer noopener\">Synthesegas<\/a>&nbsp;umgewandelt. Mithilfe der Technologie von INERATEC wird dieses&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/synthesegas\" rel=\"noreferrer noopener\">Synthesegas<\/a>&nbsp;anschlie\u00dfend in nachhaltige synthetische Kohlenwasserstoffe umgewandelt, darunter e-SAF f\u00fcr die Luftfahrt und Grundchemikalien wie e-Naphtha.<\/p>\n\n\n\n<p>Durch die Kombination von Biomasseverwertung und fortschrittlicher Kraftstoffsynthese schafft das Projekt BELair eine neue industrielle Kreislaufwertsch\u00f6pfungskette in der Region Normandie. Lokale Holzreststoffressourcen werden in nachhaltige synthetische Kraftstoffe umgewandelt, die zur&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/dekarbonisierung\" rel=\"noreferrer noopener\">Dekarbonisierung<\/a>&nbsp;der Luftfahrt und anderer schwer zu dekarbonisierender Sektoren wie der chemischen Industrie beitragen k\u00f6nnen.<\/p>\n\n\n\n<p>Das Projekt ist eine deutsch-franz\u00f6sische Industriepartnerschaft, die darauf abzielt, den Ausbau der Produktion synthetischer Kraftstoffe in Europa zu beschleunigen, und die von BPI France sowie der Region Normandie\/ELER unterst\u00fctzt wird. Das Projekt zeigt, wie bew\u00e4hrte und innovative Technologien kombiniert werden k\u00f6nnen, um eine dezentrale und widerstandsf\u00e4hige Produktion synthetischer Kraftstoffe in ganz Europa zu f\u00f6rdern. Die Partner verdeutlichen, dass sich die Kraftstoffproduktion \u00fcber regionale Wertsch\u00f6pfungsketten rasch zu einer Chance f\u00fcr die europ\u00e4ische Energiesicherheit entwickelt.<\/p>\n\n\n\n<p>Das Projekt hat die ersten technischen Phasen durchlaufen und befindet sich derzeit in der Entwicklungsphase in der N\u00e4he von Caen, wobei die Inbetriebnahme f\u00fcr 2029 geplant ist.&nbsp;<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00dcber\u00a0<strong>TERTU\u00a0<\/strong><\/h3>\n\n\n\n<p>TERTU wurde 1986 gegr\u00fcndet und hat seinen Hauptsitz in der Normandie, Frankreich. Das Unternehmen ist ein f\u00fchrender Entwickler und Hersteller von Verkehrssicherheitsl\u00f6sungen aus Holz und Metall. Mit einem starken Bekenntnis zu Innovation und Nachhaltigkeit expandiert das Unternehmen in den Bereich der gr\u00fcnen Energie, indem es seine Biomasse-Reststoffe innerhalb kreislaufwirtschaftlicher, kohlenstoffarmer industrieller Wertsch\u00f6pfungsketten verwertet.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00dcber INERATEC<\/h3>\n\n\n\n<p><strong>INERATECs&nbsp;<\/strong>Ziel ist die Defossilisierung. Das Unternehmen produziert&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/e-fuels\" rel=\"noreferrer noopener\">e-Fuels<\/a>&nbsp;und e-Chemicals, also CO\u2082-neutrale Ersatzstoffe f\u00fcr fossile Brennstoffe, die in der Luftfahrt, Schifffahrt und chemischen Industrie eingesetzt werden k\u00f6nnen.<\/p>\n\n\n\n<p>In modularen und skalierbaren Anlagen werden aus erneuerbarem Wasserstoff und CO\u2082&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/synthetisches-kerosin\" rel=\"noreferrer noopener\">synthetisches Kerosin<\/a>, Benzin, Diesel, Wachse oder Methanol hergestellt. Im Juni hat INERATEC in Frankfurt die bislang gr\u00f6\u00dfte&nbsp;<a target=\"_blank\" href=\"https:\/\/www.ineratec.de\/de\/glossar\/e-fuels\" rel=\"noreferrer noopener\">e-Fuels<\/a>-Anlage Europas er\u00f6ffnet. In dieser sollen j\u00e4hrlich bis zu 2.500 Tonnen nachhaltiger synthetischer Kraftstoffe produziert werden. Weitere Informationen finden Sie unter www.ineratec.com.<\/p>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Das Projekt wird durch den\u00a0<strong>Europ\u00e4ischen Landwirtschaftsfonds f\u00fcr regionale Entwicklung<\/strong>\u00a0(FEDER) kofinanziert.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das deutsche Cleantech-Unternehmen INERATEC und der franz\u00f6sische Industriekonzern TERTU haben das Joint Venture T.H2 gegr\u00fcndet und damit einen wichtigen Schritt zur Entwicklung einer gemeinsamen Anlage zur Herstellung synthetischer Kraftstoffe in der N\u00e4he von Caen in der Normandie getan. Die Anlage wird im Rahmen des Projekts \u201eBELair\u201c entwickelt, f\u00fcr das die Partner derzeit einen Antrag beim [&#8230;]<\/p>\n","protected":false},"author":59,"featured_media":175258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","nova_meta_subtitle":"Die Anlage wird j\u00e4hrlich etwa 60.000 Tonnen Holzreststoffe verarbeiten, die aus den regionalen W\u00e4ldern und der Industrie stammen","footnotes":""},"categories":[5572],"tags":[25075,22172,25139,11841,18769,22967],"supplier":[9205,25943,9954,27736],"class_list":["post-175232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bio-based","tag-bioreststoffe","tag-esaf","tag-holzbasiert","tag-kreislaufwirtschaft","tag-synthesegas","tag-synthetischekraftstoffe","supplier-bpifrance","supplier-eu-innovationsfonds","supplier-ineratec","supplier-tertu"],"_links":{"self":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/175232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/comments?post=175232"}],"version-history":[{"count":0,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/175232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/media\/175258"}],"wp:attachment":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/media?parent=175232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/categories?post=175232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/tags?post=175232"},{"taxonomy":"supplier","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier?post=175232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}