{"id":135139,"date":"2023-11-28T07:07:00","date_gmt":"2023-11-28T06:07:00","guid":{"rendered":"https:\/\/renewable-carbon.eu\/news\/?p=135139"},"modified":"2023-11-23T10:28:24","modified_gmt":"2023-11-23T09:28:24","slug":"studenten-entwickeln-konzept-zum-schwarzlaugen-recycling","status":"publish","type":"post","link":"https:\/\/renewable-carbon.eu\/news\/studenten-entwickeln-konzept-zum-schwarzlaugen-recycling\/","title":{"rendered":"Studenten entwickeln Konzept zum Schwarzlaugen-Recycling"},"content":{"rendered":"\n\n\n<p><strong>Im VDI-Wettbewerb \u201echemPLANT\u201c haben Studierende des Fachbereichs Chemieingenieurwesen ein Konzept entwickelt, um aus Schwarzlauge Lignin zu isolieren und dies zu Phenolderivaten weiterzuverarbeiten.<\/strong><\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"588\" src=\"https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8.jpeg\" alt=\"kjVI\" class=\"wp-image-135143\" srcset=\"https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8.jpeg 1200w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8-300x147.jpeg 300w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8-1024x502.jpeg 1024w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8-150x74.jpeg 150w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8-768x376.jpeg 768w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-8-400x196.jpeg 400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Die Masterstudenten Arvid Kunth, Malte Krechting, Nils Kulawik, Marc Siegel und Cem Hanrath (v.l.) haben f\u00fcr den VDI-Wettbewerb \u201echemPLANT\u201c eine Anlage konzipiert, die aus Schwarzlauge Lignin gewinnt und dies zu Phenol weiterverarbeitet. <strong>\u00a9<\/strong> kjVI<\/figcaption><\/figure><\/div>\n\n\n<p>Nebenprodukte aus der Papierindustrie nutzen, um die Chemieindustrie nachhaltiger zu gestalten \u2013 dar\u00fcber haben sich die Masterstudenten Cem Hanrath, Marc Siegel, Nils Kulawik, Malte Krechting und Arvid Kunth am Fachbereich Chemieingenieurwesen unserer Hochschule Gedanken gemacht. Im Rahmen des Wettbewerbs \u201echemPLANT\u201c, ausgerichtet vom Verein Deutscher Ingenieure (VDI), haben sie die theoretische Grundlage f\u00fcr eine Anlage geschaffen, die unter hohem Wasserstoffdruck Phenolderivate aus Schwarzlauge, einem Nebenprodukt in der Papierherstellung, gewinnt. Mit seinem Konzept \u201eLigno2Chemicals\u201c wurde das Team nach Berlin eingeladen, um im Rahmen der Fachtagung ECCE &amp; ECAB sein entwickeltes Verfahren in der Endrunde vorzustellen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eNormalerweise wird Schwarzlauge in der Papierfabrik lediglich thermisch verwertet \u2013 also verbrannt\u201c, erkl\u00e4rt Siegel. \u201eDoch in der Schwarzlauge steckt auch jede Menge Lignin, das wir in unserer theoretischen Arbeit durch eine Prozesssimulation des Hydrocrackings in Phenol und verschiedene Derivate aufgespaltet haben.\u201c <\/p>\n<\/blockquote>\n\n\n\n<p>Phenol, das in der Chemieindustrie unter anderem als Ausgangsstoff zur Herstellung von Kunststoffen verwendet wird, werde eigentlich aus fossilen Rohstoffen gewonnen, erl\u00e4utern die Studierenden. Das bei der Papierherstellung anfallende Biopolymer Lignin bietet die M\u00f6glichkeit, die Phenolproduktion nachhaltiger zu gestalten. \u201eWir haben f\u00fcr den Wettbewerb eine m\u00f6gliche Anlage zur Gewinnung des Lignins aus der Schwarzlauge und dessen weitere Verarbeitung entworfen.\u201c F\u00fcr das Hydrocracking, bei dem ein Stoff durch hohen Wasserstoffdruck an einem geeinigten Katalysator gespalten wird, will das Team gr\u00fcnen Wasserstoff verwenden, der in einem mit erneuerbaren Energien angetriebenen Elektrolyseur produziert wird.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10-1024x678.png\" alt=\"\" class=\"wp-image-135142\" style=\"width:400px\" srcset=\"https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10-1024x678.png 1024w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10-300x199.png 300w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10-150x99.png 150w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10-768x509.png 768w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10-400x265.png 400w, https:\/\/renewable-carbon.eu\/news\/media\/2023\/11\/image-10.png 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Die Studierenden haben mit Prof. Dr. Andreas W\u00e4sche (L) im Labor f\u00fcr nachhaltige Prozesstechnik und Biochemie gearbeitet. <strong>\u00a9<\/strong> FH M\u00fcnster \/ Frederik Tebbe<\/figcaption><\/figure><\/div>\n\n\n<p>Die Idee f\u00fcr das Projekt haben die Studierenden gemeinsam mit Prof. Dr. Andreas W\u00e4sche im Labor f\u00fcr nachhaltige Prozesstechnik und Biochemie entworfen. Innerhalb von drei Monaten haben die jungen Verfahrensingenieure ein umfangreiches Anlagenkonzept entwickelt, welches die Auslegung und Simulation wichtiger Anlagenkomponenten beinhaltet. Mithilfe einer Prozesssimulation haben sie die Phenolproduktion optimiert. Ihre Ergebnisse haben sie der Jury des VDI-Wettbewerbs im Rahmen einer Posterpr\u00e4sentation in Berlin vorgestellt.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eDer chemPLANT-Wettbewerb ist eine tolle M\u00f6glichkeit, um im Team gemeinsam an einem wissenschaftlichen Projekt zu arbeiten, kreativ zu werden und eigenst\u00e4ndig L\u00f6sungen f\u00fcr Probleme in der Industrie zu finden\u201c, so Kunth. \u201eWir k\u00f6nnen allen Studierenden nur empfehlen, daran teilzunehmen.\u201c<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Im VDI-Wettbewerb \u201echemPLANT\u201c haben Studierende des Fachbereichs Chemieingenieurwesen ein Konzept entwickelt, um aus Schwarzlauge Lignin zu isolieren und dies zu Phenolderivaten weiterzuverarbeiten. Nebenprodukte aus der Papierindustrie nutzen, um die Chemieindustrie nachhaltiger zu gestalten \u2013 dar\u00fcber haben sich die Masterstudenten Cem Hanrath, Marc Siegel, Nils Kulawik, Malte Krechting und Arvid Kunth am Fachbereich Chemieingenieurwesen unserer Hochschule [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":135143,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","nova_meta_subtitle":"Nutzung von Nebenprodukten der Papierindustrie f\u00fcr eine nachhaltigere chemische Industrie","footnotes":""},"categories":[17143],"tags":[12471,18660,19323,15124,11828,23091],"supplier":[1260,1246],"class_list":["post-135139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recycling","tag-biopolymer","tag-chemischesrecycling","tag-grunerwasserstoff","tag-katalysator","tag-lignin","tag-schwarzlaugen","supplier-fachhochschule-muenster","supplier-verein-deutscher-ingenieure-ev-vdi"],"_links":{"self":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/135139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/comments?post=135139"}],"version-history":[{"count":0,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/135139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/media\/135143"}],"wp:attachment":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/media?parent=135139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/categories?post=135139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/tags?post=135139"},{"taxonomy":"supplier","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier?post=135139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}