{"id":11638,"date":"2009-06-02T00:00:00","date_gmt":"2009-06-01T22:00:00","guid":{"rendered":"http:\/\/www.bio-based.eu\/news\/index.php?startid=20090602-03n"},"modified":"2009-06-02T00:00:00","modified_gmt":"2009-06-01T22:00:00","slug":"polen-biomassekraftwerke-im-kommen","status":"publish","type":"post","link":"https:\/\/renewable-carbon.eu\/news\/polen-biomassekraftwerke-im-kommen\/","title":{"rendered":"Polen: Biomassekraftwerke im Kommen"},"content":{"rendered":"<p><b>In Polen wird der Bau von Biomasse-Gro\u00dfkraftwerken forciert. So sind ein 183 MW Kraftwerk in Szczecin (Stettin) und  ein 80 MW Biomassekraftwerk in Swiecie s\u00fcdlich von Danzig entstanden. <\/p>\n<p>Biomassekraftwerk Swiecie (80 MW)<\/b><br \/>Der Investor Saturn Management, ein Tochterunternehmen des polnischen Energieversorgers Polish Energy Partners SA will in Swiecie einen bestehenden Kohle-Kessel auf Biomasse umr\u00fcsten. Von der Europ\u00e4ischen Bank f\u00fcr Wiederaufbau (EBRD) wird das Projekt mit einem 30 Mio. \u20ac Kredit unterst\u00fctzt. Strom und W\u00e4rme sollen an das benachbarte Mondi- Papier- und Zellstoffwerk geliefert werden.<\/p>\n<p><b>Biomassekraftwerk Szczecin (183 MW)<\/b><br \/>Der finnische Maschinenbauer Metso baut in Szczecin (Stettin) ein 183 MW Biomassekraftwerk. Auftraggeber ist der polnische Energieversorger PGE Zesp\u00f3l Elektrowni Dolna Odra S.A.. Die Investitionskosten liegen bei 60 Mio. \u20ac. Als Brennstoff sollen Hiebsreste aus der Forstwirtschaft, Weiden-Hackschnitzel aus den in der Region bereits etablierten Kurzumtriebsplantagen sowie Stroh-Pellets dienen. Die Anlage mit Kraft-W\u00e4rme-Kopplung ersetzt ein Kohle-Kraftwerk.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>In Polen wird der Bau von Biomasse-Gro&szlig;kraftwerken forciert. So sind ein 183 MW Kraftwerk in Szczecin (Stettin) und  ein 80 MW Biomassekraftwerk in Swiecie<\/b><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","nova_meta_subtitle":"","footnotes":""},"categories":[5572],"tags":[],"supplier":[1255,1253],"class_list":["post-11638","post","type-post","status-publish","format-standard","hentry","category-bio-based","supplier-metso","supplier-polish-energy-partners-sa"],"_links":{"self":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/11638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/comments?post=11638"}],"version-history":[{"count":0,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/posts\/11638\/revisions"}],"wp:attachment":[{"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/media?parent=11638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/categories?post=11638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/tags?post=11638"},{"taxonomy":"supplier","embeddable":true,"href":"https:\/\/renewable-carbon.eu\/news\/wp-json\/wp\/v2\/supplier?post=11638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}